{"id":5532,"date":"2026-09-02T12:20:14","date_gmt":"2026-09-02T15:20:14","guid":{"rendered":"https:\/\/blogomorangodonordeste.com.br\/?p=5532"},"modified":"2026-09-02T12:20:14","modified_gmt":"2026-09-02T15:20:14","slug":"pf-deflagra-operacao-contra-grupo-suspeito-de-desviar-cartoes-bancarios-em-bacabal","status":"publish","type":"post","link":"https:\/\/blogomorangodonordeste.com.br\/index.php\/2026\/09\/02\/pf-deflagra-operacao-contra-grupo-suspeito-de-desviar-cartoes-bancarios-em-bacabal\/","title":{"rendered":"PF deflagra opera\u00e7\u00e3o contra grupo suspeito de desviar cart\u00f5es banc\u00e1rios em Bacabal"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5533\" src=\"https:\/\/blogomorangodonordeste.com.br\/wp-content\/uploads\/2026\/09\/IMG-20260902-WA0048.jpg\" alt=\"\" width=\"1131\" height=\"720\" srcset=\"https:\/\/blogomorangodonordeste.com.br\/wp-content\/uploads\/2026\/09\/IMG-20260902-WA0048.jpg 1131w, https:\/\/blogomorangodonordeste.com.br\/wp-content\/uploads\/2026\/09\/IMG-20260902-WA0048-300x191.jpg 300w, https:\/\/blogomorangodonordeste.com.br\/wp-content\/uploads\/2026\/09\/IMG-20260902-WA0048-1024x652.jpg 1024w, https:\/\/blogomorangodonordeste.com.br\/wp-content\/uploads\/2026\/09\/IMG-20260902-WA0048-768x489.jpg 768w\" sizes=\"auto, (max-width: 1131px) 100vw, 1131px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>A Pol\u00edcia Federal deflagrou, nesta quarta-feira (2), a Opera\u00e7\u00e3o Selo Corrompido, que investiga a atua\u00e7\u00e3o de um grupo criminoso suspeito de desviar cart\u00f5es banc\u00e1rios para obter vantagens indevidas por meio de movimenta\u00e7\u00f5es fraudulentas em contas de terceiros e benef\u00edcios previdenci\u00e1rios.<\/p>\n<p>&nbsp;<\/p>\n<p>Ao todo, est\u00e3o sendo cumpridos cinco mandados de busca e apreens\u00e3o no munic\u00edpio de Bacabal, no Maranh\u00e3o. As ordens judiciais fazem parte das medidas adotadas pela PF para avan\u00e7ar na apura\u00e7\u00e3o do esquema.<\/p>\n<p>&nbsp;<\/p>\n<p>As investiga\u00e7\u00f5es come\u00e7aram ap\u00f3s uma comunica\u00e7\u00e3o feita pela Empresa Brasileira de Correios e Tel\u00e9grafos (ECT), que identificou ind\u00edcios de desvio de correspond\u00eancias contendo cart\u00f5es banc\u00e1rios dentro da ag\u00eancia dos Correios. A apura\u00e7\u00e3o aponta ainda para uma poss\u00edvel participa\u00e7\u00e3o de um funcion\u00e1rio da empresa p\u00fablica.<\/p>\n<p>&nbsp;<\/p>\n<p>Segundo os elementos reunidos durante a investiga\u00e7\u00e3o, o esquema teria como uma das pr\u00e1ticas a intercepta\u00e7\u00e3o de cart\u00f5es banc\u00e1rios enviados a seus destinat\u00e1rios. Entre os alvos estariam, inclusive, pessoas j\u00e1 falecidas que mantinham valores consider\u00e1veis em contas banc\u00e1rias.<\/p>\n<p>&nbsp;<\/p>\n<p>A Pol\u00edcia Federal identificou ind\u00edcios de uma atua\u00e7\u00e3o coordenada entre diferentes investigados. Entre as condutas apuradas est\u00e3o tentativas de retirada de correspond\u00eancias que continham cart\u00f5es banc\u00e1rios e o uso de documentos falsos para viabilizar as fraudes.<\/p>\n<p>&nbsp;<\/p>\n<p>A opera\u00e7\u00e3o busca reunir novos elementos de prova sobre a atua\u00e7\u00e3o do grupo, identificar todos os envolvidos e esclarecer a extens\u00e3o dos poss\u00edveis desvios e das movimenta\u00e7\u00f5es fraudulentas realizadas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; A Pol\u00edcia Federal deflagrou, nesta quarta-feira (2), a Opera\u00e7\u00e3o Selo Corrompido, que investiga a atua\u00e7\u00e3o de um grupo criminoso suspeito de desviar cart\u00f5es banc\u00e1rios para obter vantagens indevidas por meio de movimenta\u00e7\u00f5es fraudulentas em contas de terceiros e benef\u00edcios previdenci\u00e1rios. &nbsp; Ao todo, est\u00e3o sendo cumpridos cinco mandados de busca e apreens\u00e3o no [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"yst_prominent_words":[],"class_list":["post-5532","post","type-post","status-publish","format-standard","hentry","category-noticia-geral"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/blogomorangodonordeste.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5532","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogomorangodonordeste.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogomorangodonordeste.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogomorangodonordeste.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogomorangodonordeste.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=5532"}],"version-history":[{"count":1,"href":"https:\/\/blogomorangodonordeste.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5532\/revisions"}],"predecessor-version":[{"id":5534,"href":"https:\/\/blogomorangodonordeste.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5532\/revisions\/5534"}],"wp:attachment":[{"href":"https:\/\/blogomorangodonordeste.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=5532"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogomorangodonordeste.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=5532"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogomorangodonordeste.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=5532"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/blogomorangodonordeste.com.br\/index.php\/wp-json\/wp\/v2\/yst_prominent_words?post=5532"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}